{"id":25726,"date":"2019-08-08T08:33:39","date_gmt":"2019-08-08T06:33:39","guid":{"rendered":"https:\/\/lufthous.es\/lh\/?page_id=25726"},"modified":"2026-06-15T16:26:31","modified_gmt":"2026-06-15T14:26:31","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/lufthous.es\/lh\/aviso-legal\/","title":{"rendered":"Aviso legal"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text css=\u00bb.vc_custom_1781533578666{padding-top: 5% !important;padding-right: 15% !important;padding-left: 15% !important;}\u00bb]<\/p>\n<h2 class=\"p1\" style=\"text-align: center;\"><span class=\"s1\"><b>AVISO LEGAL<\/b><\/span><\/h2>\n<div>\n<p>EL presente Aviso Legal regula el acceso, navegaci\u00f3n y uso de la p\u00e1gina web \u201c<a href=\"https:\/\/www.lufthous.es\"><u>https:\/\/www.lufthous.es<\/u><\/a>\u201d en adelante \u201cla Web\u201d, cuya titularidad corresponde a<b>\u00a0OMNITRADE DYNAMICS, SL<\/b>\u00a0(en lo sucesivo Lufthous) con domicilio en la calle MARGARITA, 34, 28970, HUMANES DE MADRID (MADRID), con\u00a0<b>CIF B70680004<\/b>\u00a0Tel\u00e9fono: 900 820 300 y correo electr\u00f3nico\u00a0 <a href=\"mailto:atencioncliente@companylh.com\"><u>atencioncliente@companylh.com<\/u><\/a><\/p>\n<\/div>\n<p class=\"p1\"><span class=\"s1\">Si desea contactar con LUFTHOUS puede hacerlo por escrito en la direcci\u00f3n facilitada anteriormente, o si lo prefiere, a trav\u00e9s del tel\u00e9fono 91 144 11 79 y la direcci\u00f3n de correo electr\u00f3nico <a>info@lufthous.es<\/a>.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El acceso y utilizaci\u00f3n de la Web le atribuyen la condici\u00f3n de Usuario, lo cual implica la adhesi\u00f3n al presente Aviso Legal en la versi\u00f3n publicada en el momento en que se acceda a la misma. Si no estuviera de acuerdo con el mismo, deber\u00e1 abstenerse de acceder a la Web o de utilizar los servicios que se prestan a trav\u00e9s de la misma.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El presente Aviso Legal se rige por los principios de legalidad y de buena fe, comprometi\u00e9ndose el Usuario a utilizar la Web, as\u00ed como la informaci\u00f3n suministrada, de conformidad con la ley, la moral, las buenas costumbres y el orden p\u00fablico. La utilizaci\u00f3n no autorizada de la informaci\u00f3n contenida en esta Web (textos, im\u00e1genes, fotograf\u00edas, dise\u00f1os, videos, recetas o fichas de producto) su reventa as\u00ed como la lesi\u00f3n de derechos de terceros, dar\u00e1n lugar a las responsabilidades legalmente establecidas.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">LUFTHOUS se reserva el derecho a modificar, en cualquier momento y sin previo aviso, la presentaci\u00f3n y configuraci\u00f3n de la Web, as\u00ed como el Aviso Legal de la misma. Por ello, LUFTHOUS recomienda al Usuario leer este Aviso Legal atentamente cada vez que acceda a la Web.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El acceso a determinados Contenidos (\u201cprofesional sanitario\u201d) ofrecidos a trav\u00e9s de la Web puede encontrarse sometido a ciertas condiciones particulares propias que, seg\u00fan los casos, sustituyen, completan y\/o modifican este Aviso Legal. Por tanto, con anterioridad al acceso y\/o utilizaci\u00f3n de dichos Contenidos, Productos y\/o Servicios, el Usuario ha de leer atentamente tambi\u00e9n las correspondientes condiciones particulares. En caso de existir discrepancia entre lo establecido en el presente Aviso Legal y las condiciones particulares de cada servicio espec\u00edfico, prevalecer\u00e1 lo dispuesto en \u00e9stas \u00faltimas.<\/span><\/p>\n<p class=\"p3\"><span class=\"s1\">LUFTHOUS no se responsabiliza por el mal uso o apropiaci\u00f3n indebida de los contenidos o informaci\u00f3n publicada en la Web. El usuario reconoce y acepta que toda la informaci\u00f3n y\/o contenidos a los que acceda a trav\u00e9s de la Web lo es para su \u00fanico y exclusivo uso informativo e intransferible. Queda prohibida la cesi\u00f3n a terceros de cualquier tipo y forma de toda o parte de la informaci\u00f3n y\/o contenidos a los que pueda tener acceso el usuario a trav\u00e9s de la Web.<\/span><\/p>\n<p class=\"p3\"><span class=\"s1\">En cumplimiento de lo establecido por el art\u00edculo 21 de la Ley de Servicios de la Sociedad de la Informaci\u00f3n, LUFTHOUS podr\u00e1 remitirle, por correo electr\u00f3nico o a trav\u00e9s de cualquier otro medio an\u00e1logo, informaci\u00f3n publicitaria relacionada con la actividad de LUFTHOUS. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Derechos de Propiedad Intelectual e Industrial<\/b><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">LUFTHOUS es la \u00fanica y exclusiva titular de los derechos de propiedad intelectual e industrial sobre las marcas, im\u00e1genes, textos, dise\u00f1os, animaciones, programaci\u00f3n y dise\u00f1o de la Web o cualquier otro contenido o elementos del mismo, o, en su caso, dispone de los permisos o licencias necesarias para su utilizaci\u00f3n. El Usuario reconoce y acepta que el acceso y\/o descarga de cualquier contenido y\/o elemento que se encuentre a su disposici\u00f3n a trav\u00e9s de la Web es para su uso personal\/profesional e intransferible. Cualquier acto de reproducci\u00f3n, distribuci\u00f3n, comunicaci\u00f3n p\u00fablica, puesta a disposici\u00f3n, o transformaci\u00f3n, as\u00ed como cualquier otra forma de explotaci\u00f3n de todo o parte de dichos contenidos o elementos, realizado bajo cualquier forma o mediante cualquier medio, requerir\u00e1 el consentimiento previo y por escrito de LUFTHOUS. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Asimismo, todos los signos distintivos que aparecen en el sitio web o son titularidad de LUFTHOUS o cuenta con las correspondientes licencias, y se encuentran debidamente registrados, quedando prohibida su reproducci\u00f3n o distribuci\u00f3n bajo ning\u00fan medio, sin la debida, previa y expresa autorizaci\u00f3n de su titular.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El acceso y navegaci\u00f3n por la Web en ning\u00fan caso se entender\u00e1 como una renuncia, transmisi\u00f3n, licencia o cesi\u00f3n total ni parcial de los derechos antes indicados por parte de LUFTHOUS o, en su caso, del titular de los derechos al que correspondan.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Links<\/b><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">La Web podr\u00e1 incluir hiperv\u00ednculos a otras p\u00e1ginas web o recursos gestionados por terceras partes que no sean de LUFTHOUS, incluidos anunciantes. LUFTHOUS no ha revisado todas las p\u00e1ginas web vinculadas a esta p\u00e1gina web y no se hace responsable del contenido o veracidad de estas p\u00e1ginas web externas ni tampoco de la disponibilidad de dichas p\u00e1ginas web o recursos externos; y no aprueba ni se responsabiliza, de forma directa o indirecta, de las pr\u00e1cticas de privacidad o del contenido de estas p\u00e1ginas web, incluyendo (sin restricciones) cualquier publicidad, producto u otros materiales o servicios de la p\u00e1gina web o disponibles en dichas p\u00e1ginas web o recursos, ni por da\u00f1os, p\u00e9rdidas o infracciones causados, o presuntamente causados, por el uso, o en relaci\u00f3n con el uso o dependientes de dicho contenido, bienes o servicios disponibles en dichas p\u00e1ginas web o recursos externos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Pol\u00edtica de privacidad \/ Cookies<\/b><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Para ver la Pol\u00edtica de Privacidad de usuarios pincha [<span class=\"s3\"><a href=\"https:\/\/www.lufthous.es\/wp\/politica-de-privacidad\/\">aqu\u00ed<\/a>]<\/span>y la Pol\u00edtica en el uso de cookies\u00a0<\/span><span class=\"s1\">y pincha [<span class=\"s3\"><a href=\"https:\/\/www.lufthous.es\/wp\/contact\/politica-de-cookies\/\">aqu\u00ed<\/a>]<\/span><\/span><span class=\"s3\">. <\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Exenci\u00f3n de responsabilidad<\/b><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">LUFTHOUS ha adoptado las medidas necesarias para asegurar el correcto funcionamiento de la Web. No obstante, LUFTHOUS no ser\u00e1 responsable de falta de disponibilidad de la Web en un momento determinado, ya sea por causas t\u00e9cnicas, tareas de mantenimiento del sistema, interferencias, interrupciones de los suministradores del servicio Internet o por cualquier otra causa o fallos que se produjeran en el acceso, funcionamiento y operatividad de la Web, as\u00ed como tampoco de las interrupciones, suspensiones o el mal funcionamiento de la misma por causas ajenas a LUFTHOUS. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">LUFTHOUS excluye cualquier responsabilidad por los da\u00f1os y perjuicios de toda naturaleza que puedan deberse a la falta de disponibilidad o de continuidad del funcionamiento de la Web, a la defraudaci\u00f3n de la utilidad que los Usuarios hubieren podido atribuir a la Web, a la falibilidad de la Web, y en particular, aunque no de modo exclusivo, a los fallos en el acceso a las distintas p\u00e1ginas de la Web o a aquellas desde las que se presta el servicio.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">LUFTHOUS no controla ni garantiza la ausencia de virus ni de otros elementos en los Contenidos que puedan producir alteraciones en su sistema inform\u00e1tico (software y hardware) o en los documentos electr\u00f3nicos y ficheros almacenados en su sistema inform\u00e1tico.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">LUFTHOUS excluye cualquier responsabilidad por los da\u00f1os y perjuicios de toda naturaleza que puedan deberse a la presencia de virus o a la presencia de otros elementos en los contenidos que puedan producir alteraciones en el sistema inform\u00e1tico, documentos electr\u00f3nicos o ficheros de los Usuarios.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">LUFTHOUS no garantiza que el contenido de la Web est\u00e9 actualizado, sea completo y exacto o que el contenido no contenga defectos, errores y\/o virus. En ning\u00fan caso LUFTHOUS ser\u00e1 responsable de la producci\u00f3n de cualquier tipo de da\u00f1o que los Usuarios o terceros pudiesen ocasionar en la Web.\u00a0<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">LUFTHOUS excluye con toda la extensi\u00f3n permitida por el ordenamiento jur\u00eddico, cualquier responsabilidad por los da\u00f1os y perjuicios de toda naturaleza que pudieran deberse al acceso a la Web por personas no autorizadas, al conocimiento que puedan tener terceros no autorizados de la clase, condiciones, caracter\u00edsticas y circunstancias del uso que los Usuarios hacen de la Web; a la transmisi\u00f3n, difusi\u00f3n, almacenamiento, puesta a disposici\u00f3n, recepci\u00f3n, obtenci\u00f3n o acceso a los contenidos, y en particular, aunque no de modo exclusivo, por los da\u00f1os y perjuicios que puedan deberse a:<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\"><strong>(I)<\/strong>el incumplimiento de la ley, la moral y las buenas costumbres generalmente aceptadas o el orden p\u00fablico como consecuencia de la transmisi\u00f3n, difusi\u00f3n, almacenamiento, puesta a disposici\u00f3n, recepci\u00f3n, obtenci\u00f3n o acceso a la Web y sus contenidos; <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><strong>(II)<\/strong>la infracci\u00f3n de los derechos de propiedad intelectual e industrial, de los secretos empresariales, de compromisos contractuales de cualquier clase, de los derechos al honor, a la intimidad personal y familiar y a la imagen de las personas, de los derechos de propiedad y de toda otra naturaleza pertenecientes a un tercero como consecuencia de la transmisi\u00f3n, difusi\u00f3n, almacenamiento, puesta a disposici\u00f3n, recepci\u00f3n, obtenci\u00f3n o acceso a la Web y sus contenidos; <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><strong>(III)<\/strong>la realizaci\u00f3n de actos de competencia desleal y publicidad il\u00edcita como consecuencia de la transmisi\u00f3n, difusi\u00f3n, almacenamiento, puesta a disposici\u00f3n, recepci\u00f3n, obtenci\u00f3n o acceso a la Web y sus contenidos.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\"><b>Ley aplicable y Jurisdicci\u00f3n:<\/b><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">El presente Aviso Legal se rige por la legislaci\u00f3n espa\u00f1ola. Para conocer de cualquier controversia o litigio ser\u00e1n competentes los Juzgados y <\/span><span class=\"s4\">Tribunales de MADRID,<\/span><span class=\"s1\">con renuncia expresa de las partes a cualquier otro fuero, salvo que la ley que resulte de aplicaci\u00f3n disponga lo contrario.<\/span><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=\u00bb.vc_custom_1781533578666{padding-top: 5% !important;padding-right: 15% !important;padding-left: 15% !important;}\u00bb] AVISO LEGAL EL presente Aviso Legal regula el acceso, navegaci\u00f3n y uso&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25726","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/lufthous.es\/lh\/wp-json\/wp\/v2\/pages\/25726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lufthous.es\/lh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lufthous.es\/lh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lufthous.es\/lh\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lufthous.es\/lh\/wp-json\/wp\/v2\/comments?post=25726"}],"version-history":[{"count":7,"href":"https:\/\/lufthous.es\/lh\/wp-json\/wp\/v2\/pages\/25726\/revisions"}],"predecessor-version":[{"id":54852,"href":"https:\/\/lufthous.es\/lh\/wp-json\/wp\/v2\/pages\/25726\/revisions\/54852"}],"wp:attachment":[{"href":"https:\/\/lufthous.es\/lh\/wp-json\/wp\/v2\/media?parent=25726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}